{"id":3851,"date":"2025-01-30T09:16:10","date_gmt":"2025-01-30T08:16:10","guid":{"rendered":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1.jpg"},"modified":"2025-01-30T09:16:10","modified_gmt":"2025-01-30T08:16:10","slug":"018-vicenza-2024-2","status":"inherit","type":"attachment","link":"https:\/\/giorgiosoldi.it\/index.php\/en\/2025\/01\/30\/vicenza-2\/018-vicenza-2024-2\/","title":{"rendered":"018.Vicenza 2024"},"author":3,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-3851","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-300x201.jpg 300w, https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-768x515.jpg 768w, https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1.jpg 912w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":912,"height":612,"file":"2025\/01\/018.Vicenza-2024-1.jpg","filesize":308751,"sizes":{"medium":{"file":"018.Vicenza-2024-1-300x201.jpg","width":300,"height":201,"filesize":29788,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-300x201.jpg"},"thumbnail":{"file":"018.Vicenza-2024-1-150x150.jpg","width":150,"height":150,"filesize":23197,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-150x150.jpg"},"medium_large":{"file":"018.Vicenza-2024-1-768x515.jpg","width":768,"height":515,"filesize":68334,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-768x515.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"018.Vicenza-2024-1-100x100.jpg","width":100,"height":100,"filesize":20993,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1-100x100.jpg"},"full":{"file":"018.Vicenza-2024-1.jpg","width":912,"height":612,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1.jpg"}},"image_meta":{"aperture":"8","credit":"","camera":"NIKON Z f","caption":"","created_timestamp":"1710149053","copyright":"","focal_length":"120","iso":"100","shutter_speed":"0.004","title":"","orientation":"1","keywords":["Gita","Italia","Vicenza"]}},"post":3737,"source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/018.Vicenza-2024-1.jpg","_links":{"self":[{"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/media\/3851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/comments?post=3851"}]}}