{"id":3843,"date":"2025-01-30T09:15:58","date_gmt":"2025-01-30T08:15:58","guid":{"rendered":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1.jpg"},"modified":"2025-01-30T09:15:58","modified_gmt":"2025-01-30T08:15:58","slug":"010-vicenza-2024-2","status":"inherit","type":"attachment","link":"https:\/\/giorgiosoldi.it\/index.php\/en\/2025\/01\/30\/vicenza-2\/010-vicenza-2024-2\/","title":{"rendered":"010.Vicenza 2024"},"author":3,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-3843","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"202\" height=\"300\" src=\"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1-202x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1-202x300.jpg 202w, https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1.jpg 614w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":614,"height":912,"file":"2025\/01\/010.Vicenza-2024-1.jpg","filesize":605255,"sizes":{"medium":{"file":"010.Vicenza-2024-1-202x300.jpg","width":202,"height":300,"filesize":49924,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1-202x300.jpg"},"thumbnail":{"file":"010.Vicenza-2024-1-150x150.jpg","width":150,"height":150,"filesize":35115,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1-150x150.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"010.Vicenza-2024-1-100x100.jpg","width":100,"height":100,"filesize":30047,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1-100x100.jpg"},"full":{"file":"010.Vicenza-2024-1.jpg","width":614,"height":912,"mime_type":"image\/jpeg","source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"NIKON Z f","caption":"","created_timestamp":"1710144003","copyright":"","focal_length":"42","iso":"100","shutter_speed":"0.005","title":"","orientation":"1","keywords":["Gita","Italia","Vicenza"]}},"post":3737,"source_url":"https:\/\/giorgiosoldi.it\/wp-content\/uploads\/2025\/01\/010.Vicenza-2024-1.jpg","_links":{"self":[{"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/media\/3843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/giorgiosoldi.it\/index.php\/wp-json\/wp\/v2\/comments?post=3843"}]}}